{"id":4721,"count":1,"description":"","link":"https:\/\/society-zero.com\/chienotane\/archives\/tag\/%ef%bc%93%e5%a4%a7%e9%80%9a%e4%bf%a1%e3%82%ad%e3%83%a3%e3%83%aa%e3%82%a2","name":"\uff13\u5927\u901a\u4fe1\u30ad\u30e3\u30ea\u30a2","slug":"%ef%bc%93%e5%a4%a7%e9%80%9a%e4%bf%a1%e3%82%ad%e3%83%a3%e3%83%aa%e3%82%a2","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/society-zero.com\/chienotane\/wp-json\/wp\/v2\/tags\/4721"}],"collection":[{"href":"https:\/\/society-zero.com\/chienotane\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/society-zero.com\/chienotane\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/society-zero.com\/chienotane\/wp-json\/wp\/v2\/posts?tags=4721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}